{"id":300,"date":"2025-03-24T21:54:35","date_gmt":"2025-03-24T12:54:35","guid":{"rendered":"https:\/\/www.hanaimo.com\/faq\/?p=300"},"modified":"2025-03-24T22:20:41","modified_gmt":"2025-03-24T13:20:41","slug":"%e8%83%a1%e8%9d%b6%e8%98%ad%e3%83%bb%e3%81%9d%e3%81%ae%e4%bb%96%e5%95%86%e5%93%81","status":"publish","type":"post","link":"https:\/\/www.hanaimo.com\/faq\/300","title":{"rendered":"\u80e1\u8776\u862d\u30fb\u305d\u306e\u4ed6\u5546\u54c1"},"content":{"rendered":"\n<h2 id=\"link-0\" class=\"wp-block-heading is-style-default\">\u80e1\u8776\u862d<\/h2>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-s\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-style-columns-broken-3-3-2 is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" src=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_standard.jpg\" alt=\"\" class=\"wp-image-305\" srcset=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_standard.jpg 480w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_standard-300x300.jpg 300w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_standard-150x150.jpg 150w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-s\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-xl-font-size\">\u30b9\u30bf\u30f3\u30c0\u30fc\u30c9 3\u672c\u7acb<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-sm-font-size\">\uff08\u9ad8\u305570\u301c80cm\uff09<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-lg-font-size\">38,500\u5186<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" src=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_business.jpg\" alt=\"\" class=\"wp-image-301\" srcset=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_business.jpg 480w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_business-300x300.jpg 300w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_business-150x150.jpg 150w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-s\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-xl-font-size\">\u30d3\u30b8\u30cd\u30b9&nbsp;3\u672c\u7acb<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-sm-font-size\">\uff08\u9ad8\u305570\u301c80cm\uff09<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-lg-font-size\">55,000\u5186<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" src=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_crown.jpg\" alt=\"\" class=\"wp-image-306\" srcset=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_crown.jpg 480w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_crown-300x300.jpg 300w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_crown-150x150.jpg 150w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-s\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-xl-font-size\">\u30af\u30e9\u30a6\u30f3&nbsp;5\u672c\u7acb<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-sm-font-size\">\uff08\u9ad8\u305570\u301c80cm\uff09<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-lg-font-size\">66,000\u5186<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" src=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_prime.jpg\" alt=\"\" class=\"wp-image-303\" srcset=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_prime.jpg 480w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_prime-300x300.jpg 300w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_orchid_prime-150x150.jpg 150w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-s\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-xl-font-size\">\u30d7\u30e9\u30a4\u30e0&nbsp;5\u672c\u7acb<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-sm-font-size\">\uff08\u9ad8\u305570\u301c80cm\uff09<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-lg-font-size\">82,500\u5186<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-xxxl\"><\/div>\n\n\n\n<h2 id=\"link-1\" class=\"wp-block-heading is-style-default\">\u30df\u30c7\u30a3\u80e1\u8776\u862d<\/h2>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-s\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-style-columns-broken-3-3-2 is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" src=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_gcrack.jpg\" alt=\"\" class=\"wp-image-302\" srcset=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_gcrack.jpg 480w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_gcrack-300x300.jpg 300w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_gcrack-150x150.jpg 150w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-s\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-xl-font-size\">\u30df\u30c7\u30a3\u80e1\u8776\u862d<br>\u300cG\u30af\u30e9\u30c3\u30af\u300d<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-sm-font-size\">\uff08\u9ad8\u305530cm\uff09<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-lg-font-size\">7,600\u5186<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" src=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_withgreen.jpg\" alt=\"\" class=\"wp-image-304\" srcset=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_withgreen.jpg 480w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_withgreen-300x300.jpg 300w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_withgreen-150x150.jpg 150w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-s\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-xl-font-size\">\u30df\u30c7\u30a3\u80e1\u8776\u862d<br>\u300cwith\u30b0\u30ea\u30fc\u30f3\u300d<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-sm-font-size\">\uff08\u9ad8\u305530\u301c40cm\uff09<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-lg-font-size\">11,000\u5186<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" src=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_partheno.jpg\" alt=\"\" class=\"wp-image-307\" srcset=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_partheno.jpg 480w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_partheno-300x300.jpg 300w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_partheno-150x150.jpg 150w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-s\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-xl-font-size\">\u30df\u30c7\u30a32\u672c\u7acb<br>\u300c\u30d1\u30eb\u30c6\u30ce\u300d<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-sm-font-size\">\uff08\u9ad8\u305530\u301c40cm\uff09<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-lg-font-size\">13,200\u5186<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" src=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_table3.jpg\" alt=\"\" class=\"wp-image-311\" srcset=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_table3.jpg 480w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_table3-300x300.jpg 300w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_table3-150x150.jpg 150w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-s\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-xl-font-size\">\u30c6\u30fc\u30d6\u30eb3\u672c\u7acb<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-sm-font-size\">\uff08\u9ad8\u305530\u301c40cm\uff09<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-lg-font-size\">17,600\u5186<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" src=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_mix.jpg\" alt=\"\" class=\"wp-image-308\" srcset=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_mix.jpg 480w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_mix-300x300.jpg 300w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_mix-150x150.jpg 150w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-s\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-xl-font-size\">3\u8272\u3088\u305b<br>\u300c\u30df\u30c3\u30af\u30b9\u300d<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-sm-font-size\">\uff08\u9ad8\u305530\u301c40cm\uff09<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-lg-font-size\">16,500\u5186<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" src=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_silver.jpg\" alt=\"\" class=\"wp-image-309\" srcset=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_silver.jpg 480w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_silver-300x300.jpg 300w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_silver-150x150.jpg 150w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-s\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-xl-font-size\">\u30df\u30c7\u30a33\u672c\u7acb<br>\u300c\u30b7\u30eb\u30d0\u30fc\u300d<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-sm-font-size\">\uff08\u9ad8\u305530\u301c40cm\uff09<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-lg-font-size\">16,500\u5186<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" src=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_midi5.jpg\" alt=\"\" class=\"wp-image-310\" srcset=\"https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_midi5.jpg 480w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_midi5-300x300.jpg 300w, https:\/\/www.hanaimo.com\/faq\/wp-content\/uploads\/2025\/03\/about_products_midiorchid_midi5-150x150.jpg 150w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-space-s\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-xl-font-size\">\u30df\u30c7\u30a35\u672c\u7acb<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-sm-font-size\">\uff08\u9ad8\u305540\u301c50cm\uff09<\/p>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-default\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-goshic-b-font-family has-lg-font-size\">19,800\u5186<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"\u80e1\u8776\u862d \u30b9\u30bf\u30f3\u30c0\u30fc\u30c9 3\u672c\u7acb \uff08\u9ad8\u305570\u301c80cm\uff09 38,500\u5186 \u30d3\u30b8\u30cd\u30b9&nbsp;3\u672c\u7acb \uff08\u9ad8\u305570\u301c80cm\uff09 55,000\u5186 \u30af\u30e9\u30a6\u30f3&nbsp;5\u672c\u7acb \uff08\u9ad8\u305570\u301c80cm\uff09 66,00 [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-300","post","type-post","status-publish","format-standard","hentry","category-5"],"_links":{"self":[{"href":"https:\/\/www.hanaimo.com\/faq\/wp-json\/wp\/v2\/posts\/300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hanaimo.com\/faq\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hanaimo.com\/faq\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hanaimo.com\/faq\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hanaimo.com\/faq\/wp-json\/wp\/v2\/comments?post=300"}],"version-history":[{"count":2,"href":"https:\/\/www.hanaimo.com\/faq\/wp-json\/wp\/v2\/posts\/300\/revisions"}],"predecessor-version":[{"id":320,"href":"https:\/\/www.hanaimo.com\/faq\/wp-json\/wp\/v2\/posts\/300\/revisions\/320"}],"wp:attachment":[{"href":"https:\/\/www.hanaimo.com\/faq\/wp-json\/wp\/v2\/media?parent=300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hanaimo.com\/faq\/wp-json\/wp\/v2\/categories?post=300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hanaimo.com\/faq\/wp-json\/wp\/v2\/tags?post=300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}